{"id":4020,"date":"2023-03-22T15:45:42","date_gmt":"2023-03-22T14:45:42","guid":{"rendered":"https:\/\/ostinato.fr\/?post_type=tribe_events&#038;p=4020"},"modified":"2023-04-06T14:18:40","modified_gmt":"2023-04-06T12:18:40","slug":"les-etoiles-du-classique","status":"publish","type":"tribe_events","link":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/","title":{"rendered":"Les Etoiles du Classique"},"content":{"rendered":"<p>Pendant quatre jours, plus de 200 jeunes artistes de grand talent se produiront au cours<br \/>\nde 12 concerts au Th\u00e9\u00e2tre Alexandre Dumas, \u00e0 l\u2019\u00c9glise Saint-Germain et en plein air dans<br \/>\nle parc du ch\u00e2teau du Domaine National de Saint-Germain-en-Laye. D\u00e9sireux d\u2019y convier<br \/>\nun public toujours plus vari\u00e9 et nombreux, le Festival propose une grande vari\u00e9t\u00e9 de<br \/>\nconcerts : musique de chambre, concerts symphoniques en plein air, op\u00e9ra, danse, jazz et<br \/>\nautres formats insolites.<\/p>\n<h2>Artistes :<\/h2>\n<ul>\n<li>Chlo\u00e9 Dufresne, <em>direction<\/em><\/li>\n<li>Orchestre Ostinato<\/li>\n<li>\u2028Thomas Lefort, <em>violon<\/em><\/li>\n<li>Eva Zavaro, <em>violon<\/em><\/li>\n<li>Gabriel Pidoux, <em>hautbois<\/em><\/li>\n<li>\u2028Aur\u00e9lien Pascal, <em>violoncelle<\/em><\/li>\n<li>Mathilde Cald\u00e9rini, <em>fl\u00fbte<\/em><\/li>\n<li>\u2028Alexandra Luiceanu, <em>harpe<\/em><\/li>\n<\/ul>\n<h2>Programme :<\/h2>\n<div class=\"template-page content av-content-small alpha units\">\n<div class=\"post-entry post-entry-type-page post-entry-7376\">\n<div class=\"entry-content-wrapper clearfix\">\n<section class=\"av_textblock_section \">\n<div class=\"avia_textblock \">\n<p>CONCERT SYMPHONIQUE EN PLEIN AIR<br \/>\nPropos\u00e9 par l\u2019Orchestre Ostinato, dirig\u00e9 par la jeune cheffe Chlo\u00e9 Dufresne, le concert<br \/>\nsymphonique en plein air est un rendez-vous incontournable \u00e0 ne pas manquer. Il sera<br \/>\nl\u2019occasion d\u2019entendre de nombreux jeunes solistes accompagn\u00e9s de l\u2019orchestre autour de<br \/>\ngrands chefs d\u2019\u0153uvres de la musique classique. Du romantisme \u00e0 l\u2019\u00e9tat pur et de grands<br \/>\nmoments d\u2019\u00e9motions en plein air et en bonne compagnie, celle des \u00e9toiles de la nuit et<br \/>\ndes \u00e9toiles du classique.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wolfgang Amadeus MOZART<\/strong><\/p>\n<p><em>Ouverture de Cosi fan tutte K.588<br \/>\nConcerto pour fl\u00fbte et harpe K.299 (IIe et IIIe mouvement)<\/em><\/p>\n<p><strong>Johann Sebastian BACH<\/strong><\/p>\n<p><em>Concerto en r\u00e9 mineur pour hautbois et orchestre BWV 1059<\/em><br \/>\n<em>Concerto pour 2 violons et orchestre en r\u00e9<\/em><\/p>\n<p><strong>Piotr Ilitch TCHAIKOVSKY<\/strong><\/p>\n<p><em>Variations sur un th\u00e8me Rococo op. 33<\/em><\/p>\n<p><strong>Camille SAINT-SA\u00cbNS<\/strong><\/p>\n<p><em>Introduction et Rondo-Capriccioso pour violon et orchestre<\/em><\/p>\n<p><strong>Antonin DVOR\u00c1K<\/strong><\/p>\n<p><em>Romance pour violon et orchestre op.11<\/em><\/p>\n<\/div>\n<\/section>\n<section class=\"av_textblock_section \"><\/section>\n<\/div>\n<\/div>\n<\/div>\n<h2>Date :<\/h2>\n<p>Le 1er juillet 2023 \u00e0 21h30<\/p>\n<h2>Adresse :<\/h2>\n<p>Domaine National de Saint-Germain-en-Laye<\/p>\n<p><span class=\"LrzXr\">Pl. Charles de Gaulle, 78100 Saint-Germain-en-Laye<\/span><\/p>\n<h2>Ouverture de la billetterie :<\/h2>\n<p>Le 31 mars 2023<\/p>\n<p>Acc\u00e8s :<\/p>\n<p>En voiture depuis Paris (30 min)<br \/>\nParking sur place<br \/>\nEn RER A depuis Paris<br \/>\n25 min depuis Etoile, 34 min depuis Ch\u00e2telet<\/p>\n<h2>R\u00e9servations :<\/h2>\n<p><a href=\"http:\/\/www.lesetoilesduclassique.fr\">http:\/\/www.lesetoilesduclassique.fr<\/a><\/p>\n<h2>Tarifs<\/h2>\n<p>Tarif plein : 18\u20ac \u00e0 30\u20ac<br \/>\nTarif r\u00e9duit : 12\u20ac \u00e0 20\u20ac \u2028Gratuit pour :<br \/>\n-les moins de 6 ans ;<br \/>\n-les 1000 enfants ayant b\u00e9n\u00e9fici\u00e9 d&rsquo;une m\u00e9diation en milieu scolaire ;<br \/>\n-les jeunes autistes et leurs accompagnateurs<\/p>\n<p>Pass famille<br \/>\nGratuit\u00e9 d\u00e8s le second enfant<br \/>\npour les enfants (moins de 16 ans) d&rsquo;une m\u00eame famille<br \/>\n(hors op\u00e9ra et concert de cl\u00f4ture)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chlo\u00e9 Dufresne, direction<br \/>\nOrchestre Ostinato<\/p>\n<p>\u2028Thomas Lefort, violon<br \/>\nEva Zavaro, violon<br \/>\nGabriel Pidoux, hautbois<br \/>\n\u2028Aur\u00e9lien Pascal, violoncelle<br \/>\nMathilde Cald\u00e9rini, fl\u00fbte<br \/>\n\u2028Alexandra Luiceanu, harpe<\/p>\n<p>Domaine National de Saint Germaine en Laye<\/p>\n","protected":false},"author":2,"featured_media":4026,"template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","_mi_skip_tracking":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4020","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Etoiles du Classique - Ostinato - L&#039;Orchestre<\/title>\n<meta name=\"description\" content=\"CONCERT SYMPHONIQUE EN PLEIN AIR Propos\u00e9 par l\u2019Orchestre Ostinato, dirig\u00e9 par la jeune cheffe Chlo\u00e9 Dufresne, le concert symphonique en plein air est un rendez-vous incontournable \u00e0 ne pas manquer. Mozart - Bach - Tchaikovsky - Saint-Sa\u00ebns - Dvorak\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Etoiles du Classique - Ostinato - L&#039;Orchestre\" \/>\n<meta property=\"og:description\" content=\"CONCERT SYMPHONIQUE EN PLEIN AIR Propos\u00e9 par l\u2019Orchestre Ostinato, dirig\u00e9 par la jeune cheffe Chlo\u00e9 Dufresne, le concert symphonique en plein air est un rendez-vous incontournable \u00e0 ne pas manquer. Mozart - Bach - Tchaikovsky - Saint-Sa\u00ebns - Dvorak\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/\" \/>\n<meta property=\"og:site_name\" content=\"Ostinato - L&#039;Orchestre\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-06T12:18:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ostinato.fr\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-22-at-15.41.34-1024x970.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"970\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/event\\\/les-etoiles-du-classique\\\/\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/event\\\/les-etoiles-du-classique\\\/\",\"name\":\"Les Etoiles du Classique - Ostinato - L&#039;Orchestre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/event\\\/les-etoiles-du-classique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/event\\\/les-etoiles-du-classique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Screenshot-2023-03-22-at-15.41.34.png\",\"datePublished\":\"2023-03-22T14:45:42+00:00\",\"dateModified\":\"2023-04-06T12:18:40+00:00\",\"description\":\"CONCERT SYMPHONIQUE EN PLEIN AIR Propos\u00e9 par l\u2019Orchestre Ostinato, dirig\u00e9 par la jeune cheffe Chlo\u00e9 Dufresne, le concert symphonique en plein air est un rendez-vous incontournable \u00e0 ne pas manquer. Mozart - Bach - Tchaikovsky - Saint-Sa\u00ebns - Dvorak\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/event\\\/les-etoiles-du-classique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/event\\\/les-etoiles-du-classique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/event\\\/les-etoiles-du-classique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Screenshot-2023-03-22-at-15.41.34.png\",\"contentUrl\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Screenshot-2023-03-22-at-15.41.34.png\",\"width\":1580,\"height\":1496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/event\\\/les-etoiles-du-classique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ostinato.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les Etoiles du Classique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#website\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/\",\"name\":\"Ostinato - L&#039;Orchestre\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ostinato.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#organization\",\"name\":\"Ostinato - L&#039;Orchestre\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-OSTINATO-logo-officiel-300823.png\",\"contentUrl\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-OSTINATO-logo-officiel-300823.png\",\"width\":210,\"height\":68,\"caption\":\"Ostinato - L&#039;Orchestre\"},\"image\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Etoiles du Classique - Ostinato - L&#039;Orchestre","description":"CONCERT SYMPHONIQUE EN PLEIN AIR Propos\u00e9 par l\u2019Orchestre Ostinato, dirig\u00e9 par la jeune cheffe Chlo\u00e9 Dufresne, le concert symphonique en plein air est un rendez-vous incontournable \u00e0 ne pas manquer. Mozart - Bach - Tchaikovsky - Saint-Sa\u00ebns - Dvorak","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Etoiles du Classique - Ostinato - L&#039;Orchestre","og_description":"CONCERT SYMPHONIQUE EN PLEIN AIR Propos\u00e9 par l\u2019Orchestre Ostinato, dirig\u00e9 par la jeune cheffe Chlo\u00e9 Dufresne, le concert symphonique en plein air est un rendez-vous incontournable \u00e0 ne pas manquer. Mozart - Bach - Tchaikovsky - Saint-Sa\u00ebns - Dvorak","og_url":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/","og_site_name":"Ostinato - L&#039;Orchestre","article_modified_time":"2023-04-06T12:18:40+00:00","og_image":[{"width":1024,"height":970,"url":"https:\/\/ostinato.fr\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-22-at-15.41.34-1024x970.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/","url":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/","name":"Les Etoiles du Classique - Ostinato - L&#039;Orchestre","isPartOf":{"@id":"https:\/\/ostinato.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/#primaryimage"},"image":{"@id":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/#primaryimage"},"thumbnailUrl":"https:\/\/ostinato.fr\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-22-at-15.41.34.png","datePublished":"2023-03-22T14:45:42+00:00","dateModified":"2023-04-06T12:18:40+00:00","description":"CONCERT SYMPHONIQUE EN PLEIN AIR Propos\u00e9 par l\u2019Orchestre Ostinato, dirig\u00e9 par la jeune cheffe Chlo\u00e9 Dufresne, le concert symphonique en plein air est un rendez-vous incontournable \u00e0 ne pas manquer. Mozart - Bach - Tchaikovsky - Saint-Sa\u00ebns - Dvorak","breadcrumb":{"@id":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/#primaryimage","url":"https:\/\/ostinato.fr\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-22-at-15.41.34.png","contentUrl":"https:\/\/ostinato.fr\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-22-at-15.41.34.png","width":1580,"height":1496},{"@type":"BreadcrumbList","@id":"https:\/\/ostinato.fr\/index.php\/event\/les-etoiles-du-classique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ostinato.fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/ostinato.fr\/index.php\/events\/"},{"@type":"ListItem","position":3,"name":"Les Etoiles du Classique"}]},{"@type":"WebSite","@id":"https:\/\/ostinato.fr\/#website","url":"https:\/\/ostinato.fr\/","name":"Ostinato - L&#039;Orchestre","description":"","publisher":{"@id":"https:\/\/ostinato.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ostinato.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ostinato.fr\/#organization","name":"Ostinato - L&#039;Orchestre","url":"https:\/\/ostinato.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ostinato.fr\/#\/schema\/logo\/image\/","url":"https:\/\/ostinato.fr\/wp-content\/uploads\/2023\/08\/cropped-OSTINATO-logo-officiel-300823.png","contentUrl":"https:\/\/ostinato.fr\/wp-content\/uploads\/2023\/08\/cropped-OSTINATO-logo-officiel-300823.png","width":210,"height":68,"caption":"Ostinato - L&#039;Orchestre"},"image":{"@id":"https:\/\/ostinato.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/tribe_events\/4020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":10,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/tribe_events\/4020\/revisions"}],"predecessor-version":[{"id":4050,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/tribe_events\/4020\/revisions\/4050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/media\/4026"}],"wp:attachment":[{"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4020"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/tags?post=4020"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=4020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}