{"id":720,"date":"2018-10-29T12:48:03","date_gmt":"2018-10-29T11:48:03","guid":{"rendered":"https:\/\/ostinato.fr\/?page_id=720"},"modified":"2018-12-04T12:03:02","modified_gmt":"2018-12-04T11:03:02","slug":"ecouter-autrement","status":"publish","type":"page","link":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/","title":{"rendered":"Ecouter autrement"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Permettre au public ou aux salari\u00e9s de&nbsp;diriger l\u2019orchestre<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"958\" height=\"768\" src=\"https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Nous-soutenir-_-entreprises-particuliers-_entreprises-_-Ecouter-autrement-Concert-educ-As-Baguette\u00a9W-Beaucardet-20-1.jpg\" alt=\"\" class=\"wp-image-722\" srcset=\"https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Nous-soutenir-_-entreprises-particuliers-_entreprises-_-Ecouter-autrement-Concert-educ-As-Baguette\u00a9W-Beaucardet-20-1.jpg 958w, https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Nous-soutenir-_-entreprises-particuliers-_entreprises-_-Ecouter-autrement-Concert-educ-As-Baguette\u00a9W-Beaucardet-20-1-300x241.jpg 300w, https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Nous-soutenir-_-entreprises-particuliers-_entreprises-_-Ecouter-autrement-Concert-educ-As-Baguette\u00a9W-Beaucardet-20-1-768x616.jpg 768w\" sizes=\"auto, (max-width: 958px) 100vw, 958px\" \/><\/figure><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Plongez dans la musique ! Vivez des moments d&rsquo;exception, cr\u00e9ez avec nous votre concert priv\u00e9 sur mesure, \u00e0 partager avec vos invit\u00e9s !<\/p><\/blockquote>\n\n\n\n<p>Initi\u00e9 lors d\u2019un concert \u00e0 la Philharmonie de Paris, ce concept original permet \u00e0 des membres du public de prendre la place du chef d\u2019orchestre pendant quelques instants. Sensations fortes garanties !<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Ecouter-autrement.jpg\" alt=\"\" class=\"wp-image-721\" width=\"199\" height=\"108\" srcset=\"https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Ecouter-autrement.jpg 1570w, https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Ecouter-autrement-300x162.jpg 300w, https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Ecouter-autrement-768x416.jpg 768w, https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Ecouter-autrement-1024x554.jpg 1024w, https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Ecouter-autrement-1320x715.jpg 1320w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/figure><\/div>\n\n\n\n<p><em>Ecouter autrement<\/em>&nbsp; est&nbsp; un nouveau concept de concert&nbsp; pens\u00e9 par Jean-Luc Tingaud pour&nbsp;red\u00e9couvrir de mani\u00e8re ludique et didactique les grands chef-d\u2019\u0153uvres de la musique classique. Chaque concert est d\u00e9di\u00e9 \u00e0 un compositeur, \u00e9clairant ses \u0153uvres d\u2019exemples, de pr\u00e9sentations, de cl\u00e9s d\u2019\u00e9coute.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La gamme&nbsp;<em>Ecouter autrement<\/em>&nbsp;propose \u00e9galement :<\/p><cite>&#8211; Une rencontre avec les musiciens apr\u00e8s le concert : vous pouvez \u00e9changer avec eux et voir les instruments de pr\u00e8s<br>&#8211; Une plong\u00e9e au coeur de l\u2019orchestre :&nbsp;certaines places du public sont r\u00e9serv\u00e9es sur la sc\u00e8ne, parmi les musiciens, afin de&nbsp;vivre le concert de l\u2019int\u00e9rieur<br>&#8211; Un atelier famille : un atelier anim\u00e9 par des musiciens de l\u2019orchestre et des animateurs pr\u00e9pare les enfants au concert qu\u2019ils \u00e9couteront avec leurs parents<\/cite><\/blockquote>\n\n\n\n<p>Nous adaptons le concert \u00e0 l\u2019\u00e9v\u00e9nement que vous souhaitez proposer : taille de l\u2019orchestre, choix de la salle, dur\u00e9e du concert, type de public vis\u00e9\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Permettre au public ou aux salari\u00e9s de&nbsp;diriger l\u2019orchestre Plongez dans la musique ! Vivez des moments d&rsquo;exception, cr\u00e9ez avec nous votre concert priv\u00e9 sur mesure, \u00e0 partager avec vos invit\u00e9s<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/\" class=\"home-blog-btn\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","_exactmetrics_skip_tracking":false,"footnotes":""},"class_list":["post-720","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecouter autrement - Ostinato - L&#039;Orchestre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecouter autrement - Ostinato - L&#039;Orchestre\" \/>\n<meta property=\"og:description\" content=\"Permettre au public ou aux salari\u00e9s de&nbsp;diriger l\u2019orchestre Plongez dans la musique ! Vivez des moments d&rsquo;exception, cr\u00e9ez avec nous votre concert priv\u00e9 sur mesure, \u00e0 partager avec vos invit\u00e9sLire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/\" \/>\n<meta property=\"og:site_name\" content=\"Ostinato - L&#039;Orchestre\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-04T11:03:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Nous-soutenir-_-entreprises-particuliers-_entreprises-_-Ecouter-autrement-Concert-educ-As-Baguette\u00a9W-Beaucardet-20-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/ecouter-autrement\\\/\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/ecouter-autrement\\\/\",\"name\":\"Ecouter autrement - Ostinato - L&#039;Orchestre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/ecouter-autrement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/ecouter-autrement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Ecouter-autrement.jpg\",\"datePublished\":\"2018-10-29T11:48:03+00:00\",\"dateModified\":\"2018-12-04T11:03:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/ecouter-autrement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/ecouter-autrement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/ecouter-autrement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Ecouter-autrement.jpg\",\"contentUrl\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Ecouter-autrement.jpg\",\"width\":1570,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/index.php\\\/ecouter-autrement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ostinato.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecouter autrement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#website\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/\",\"name\":\"Ostinato - L&#039;Orchestre\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ostinato.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#organization\",\"name\":\"Ostinato - L&#039;Orchestre\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-OSTINATO-logo-officiel-300823.png\",\"contentUrl\":\"https:\\\/\\\/ostinato.fr\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-OSTINATO-logo-officiel-300823.png\",\"width\":210,\"height\":68,\"caption\":\"Ostinato - L&#039;Orchestre\"},\"image\":{\"@id\":\"https:\\\/\\\/ostinato.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecouter autrement - Ostinato - L&#039;Orchestre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/","og_locale":"fr_FR","og_type":"article","og_title":"Ecouter autrement - Ostinato - L&#039;Orchestre","og_description":"Permettre au public ou aux salari\u00e9s de&nbsp;diriger l\u2019orchestre Plongez dans la musique ! Vivez des moments d&rsquo;exception, cr\u00e9ez avec nous votre concert priv\u00e9 sur mesure, \u00e0 partager avec vos invit\u00e9sLire la suite","og_url":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/","og_site_name":"Ostinato - L&#039;Orchestre","article_modified_time":"2018-12-04T11:03:02+00:00","og_image":[{"url":"https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Nous-soutenir-_-entreprises-particuliers-_entreprises-_-Ecouter-autrement-Concert-educ-As-Baguette\u00a9W-Beaucardet-20-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/","url":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/","name":"Ecouter autrement - Ostinato - L&#039;Orchestre","isPartOf":{"@id":"https:\/\/ostinato.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/#primaryimage"},"image":{"@id":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/#primaryimage"},"thumbnailUrl":"https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Ecouter-autrement.jpg","datePublished":"2018-10-29T11:48:03+00:00","dateModified":"2018-12-04T11:03:02+00:00","breadcrumb":{"@id":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/#primaryimage","url":"https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Ecouter-autrement.jpg","contentUrl":"https:\/\/ostinato.fr\/wp-content\/uploads\/2018\/10\/Ecouter-autrement.jpg","width":1570,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/ostinato.fr\/index.php\/ecouter-autrement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ostinato.fr\/"},{"@type":"ListItem","position":2,"name":"Ecouter autrement"}]},{"@type":"WebSite","@id":"https:\/\/ostinato.fr\/#website","url":"https:\/\/ostinato.fr\/","name":"Ostinato - L&#039;Orchestre","description":"","publisher":{"@id":"https:\/\/ostinato.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ostinato.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ostinato.fr\/#organization","name":"Ostinato - L&#039;Orchestre","url":"https:\/\/ostinato.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ostinato.fr\/#\/schema\/logo\/image\/","url":"https:\/\/ostinato.fr\/wp-content\/uploads\/2023\/08\/cropped-OSTINATO-logo-officiel-300823.png","contentUrl":"https:\/\/ostinato.fr\/wp-content\/uploads\/2023\/08\/cropped-OSTINATO-logo-officiel-300823.png","width":210,"height":68,"caption":"Ostinato - L&#039;Orchestre"},"image":{"@id":"https:\/\/ostinato.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/pages\/720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/comments?post=720"}],"version-history":[{"count":10,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/pages\/720\/revisions"}],"predecessor-version":[{"id":2382,"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/pages\/720\/revisions\/2382"}],"wp:attachment":[{"href":"https:\/\/ostinato.fr\/index.php\/wp-json\/wp\/v2\/media?parent=720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}